{"id":67,"count":1,"description":"","link":"https:\/\/infomedika.com\/es\/category\/salud\/","name":"Salud","slug":"salud","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud Archives - Infomedika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infomedika.com\/es\/category\/salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud Archives - Infomedika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infomedika.com\/es\/category\/salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Infomedika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/infomedika.com\\\/category\\\/salud\\\/\",\"url\":\"https:\\\/\\\/infomedika.com\\\/category\\\/salud\\\/\",\"name\":\"Salud Archives - Infomedika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infomedika.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infomedika.com\\\/category\\\/salud\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infomedika.com\\\/category\\\/salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infomedika.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infomedika.com\\\/#website\",\"url\":\"https:\\\/\\\/infomedika.com\\\/\",\"name\":\"Infomedika\",\"description\":\"We are committed to provide and maintain the healthcare industry at the forefront of information technologies in areas such as services, finance, and administration.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infomedika.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infomedika.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infomedika.com\\\/#organization\",\"name\":\"Infomedika\",\"url\":\"https:\\\/\\\/infomedika.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infomedika.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infomedika.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logos_infomedika_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\\\/\\\/infomedika.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logos_infomedika_Mesa-de-trabajo-1.png\",\"width\":4500,\"height\":1125,\"caption\":\"Infomedika\"},\"image\":{\"@id\":\"https:\\\/\\\/infomedika.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infomedika\",\"https:\\\/\\\/www.instagram.com\\\/infomedikainc\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/infomedika-inc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud Archives - Infomedika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infomedika.com\/es\/category\/salud\/","og_locale":"es_ES","og_type":"article","og_title":"Salud Archives - Infomedika","og_url":"https:\/\/infomedika.com\/es\/category\/salud\/","og_site_name":"Infomedika","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/infomedika.com\/category\/salud\/","url":"https:\/\/infomedika.com\/category\/salud\/","name":"Salud Archives - Infomedika","isPartOf":{"@id":"https:\/\/infomedika.com\/#website"},"breadcrumb":{"@id":"https:\/\/infomedika.com\/category\/salud\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/infomedika.com\/category\/salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infomedika.com\/"},{"@type":"ListItem","position":2,"name":"Salud"}]},{"@type":"WebSite","@id":"https:\/\/infomedika.com\/#website","url":"https:\/\/infomedika.com\/","name":"Infomedika","description":"We are committed to provide and maintain the healthcare industry at the forefront of information technologies in areas such as services, finance, and administration.","publisher":{"@id":"https:\/\/infomedika.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infomedika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infomedika.com\/#organization","name":"Infomedika","url":"https:\/\/infomedika.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infomedika.com\/#\/schema\/logo\/image\/","url":"https:\/\/infomedika.com\/wp-content\/uploads\/2022\/03\/logos_infomedika_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/infomedika.com\/wp-content\/uploads\/2022\/03\/logos_infomedika_Mesa-de-trabajo-1.png","width":4500,"height":1125,"caption":"Infomedika"},"image":{"@id":"https:\/\/infomedika.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infomedika","https:\/\/www.instagram.com\/infomedikainc\/","https:\/\/www.linkedin.com\/company\/infomedika-inc\/"]}]}},"_links":{"self":[{"href":"https:\/\/infomedika.com\/es\/wp-json\/wp\/v2\/categories\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infomedika.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/infomedika.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/infomedika.com\/es\/wp-json\/wp\/v2\/posts?categories=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}